{"id":17141,"date":"2022-02-24T03:30:11","date_gmt":"2022-02-24T03:30:11","guid":{"rendered":"https:\/\/www.csmiguel.pt\/web\/?p=17141"},"modified":"2022-03-07T03:31:05","modified_gmt":"2022-03-07T03:31:05","slug":"concurso-nacional-de-leitura-fase-municipal","status":"publish","type":"post","link":"https:\/\/www.csmiguel.pt\/web\/concurso-nacional-de-leitura-fase-municipal\/","title":{"rendered":"Concurso Nacional de Leitura &#8211; Fase Municipal"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-17143\" src=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/03\/leitura-mar22-0.png\" alt=\"\" width=\"300\" height=\"200\" \/>No dia 23 de fevereiro, quatro alunas do Col\u00e9gio S\u00e3o Miguel, Vit\u00f3ria Pereira, do 8.\u00ba A, Constan\u00e7a Santos, do 9.\u00ba A, Rebeca Pereira, do 11.\u00ba C e Daniela Santos, do 12.\u00ba B, participaram na Fase Municipal do Concurso Nacional de Leitura, no edif\u00edcio da C\u00e2mara Municipal de Our\u00e9m. Esta fase do concurso, organizada pelo Grupo de Trabalho Concelhio da Rede de Bibliotecas de Our\u00e9m, tem como objetivo fomentar, cada vez mais, o gosto pela leitura e destacar a sua import\u00e2ncia.<\/p>\n<p style=\"text-align: justify;\">O campeonato contou com a realiza\u00e7\u00e3o de um question\u00e1rio, uma avalia\u00e7\u00e3o oral e uma prova escrita que colocaram \u00e0 prova os conhecimentos dos participantes acerca dos livros indicados para esta fase &#8211; O rapaz ao fundo da sala, de Onjali Q. Ra\u00faf, para o 3.\u00ba ciclo, e A rapariga que lia no metro, de Christine F\u00e9ret-Fleury, para o secund\u00e1rio. Apesar do grande desafio, as alunas souberam responder \u00e0 altura, com um desempenho louv\u00e1vel.<\/p>\n<p style=\"text-align: justify;\">A pr\u00f3xima fase do concurso ir\u00e1 decorrer em Vila Nova da Barquinha, onde as alunas Daniela Santos e Rebeca Pereira ir\u00e3o representar o concelho de Our\u00e9m. Parabenizamos todos os participantes pela ades\u00e3o a esta iniciativa e desejamos boa sorte para a pr\u00f3xima fase.<\/p>\n<p style=\"text-align: right;\"><em>Rebeca Pereira, 11.\u00ba C<\/em><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-17142\" src=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/03\/leitura-mar22-1.jpg\" alt=\"\" width=\"1602\" height=\"1068\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/03\/leitura-mar22-1.jpg 1602w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/03\/leitura-mar22-1-300x200.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/03\/leitura-mar22-1-768x512.jpg 768w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/03\/leitura-mar22-1-1024x683.jpg 1024w\" sizes=\"(max-width: 1602px) 100vw, 1602px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 23 de fevereiro, quatro alunas do Col\u00e9gio S\u00e3o Miguel, Vit\u00f3ria Pereira, do 8.\u00ba A, Constan\u00e7a Santos, do 9.\u00ba A, Rebeca Pereira, do 11.\u00ba C e Daniela Santos, do 12.\u00ba B, participaram na Fase Municipal do Concurso Nacional de Leitura, no edif\u00edcio da C\u00e2mara Municipal de Our\u00e9m. Esta fase do concurso, organizada pelo Grupo de Trabalho Concelhio da Rede de Bibliotecas de Our\u00e9m, tem como objetivo fomentar, cada vez mais, o gosto pela leitura e destacar a sua import\u00e2ncia.<br ...\n<\/p>\n","protected":false},"author":5,"featured_media":17143,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":11,"footnotes":""},"categories":[95],"tags":[],"class_list":["post-17141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias1718"],"_links":{"self":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/17141"}],"collection":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/comments?post=17141"}],"version-history":[{"count":1,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/17141\/revisions"}],"predecessor-version":[{"id":17144,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/17141\/revisions\/17144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media\/17143"}],"wp:attachment":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media?parent=17141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/categories?post=17141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/tags?post=17141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}