{"id":17063,"date":"2022-02-10T18:14:51","date_gmt":"2022-02-10T18:14:51","guid":{"rendered":"https:\/\/www.csmiguel.pt\/web\/?p=17063"},"modified":"2022-02-10T18:14:51","modified_gmt":"2022-02-10T18:14:51","slug":"european-money-quiz-4","status":"publish","type":"post","link":"https:\/\/www.csmiguel.pt\/web\/european-money-quiz-4\/","title":{"rendered":"European Money Quiz"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-17066\" src=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/02\/money-quiz-fev22-0.png\" alt=\"\" width=\"300\" height=\"200\" \/>Hoje, 10 de fevereiro, foi dia de competi\u00e7\u00e3o em literacia financeira! Todos os alunos das turmas do 8.\u00ba ano, inclusive os que nos acompanharam a partir de casa, participaram na competi\u00e7\u00e3o europeia do European Money Quiz (EMQ).<\/p>\n<p style=\"text-align: justify;\">Esta iniciativa, promovida pela Associa\u00e7\u00e3o Portuguesa de Bancos visa promover a literacia financeira dos jovens entre os 13 e os 15 anos e testar os seus conhecimentos em mat\u00e9rias como a poupan\u00e7a, endividamento, gest\u00e3o do or\u00e7amento familiar, seguran\u00e7a digital, entre outras.<\/p>\n<p style=\"text-align: justify;\">Foram apurados para a fase nacional os alunos Maria La\u00edns Santos e Jo\u00e3o Vieira do 8.\u00ba C.<\/p>\n<p style=\"text-align: justify;\">A competi\u00e7\u00e3o acontece em duas fases: primeiro, as finais nacionais servem para apurar os dois vencedores por cada pa\u00eds; depois, a final europeia, onde os alunos apurados dos v\u00e1rios pa\u00edses ir\u00e3o competir frente a frente, em Bruxelas, para tentar alcan\u00e7ar o lugar de campe\u00f5es europeus do EMQ.<\/p>\n<p style=\"text-align: justify;\">Boa sorte aos nossos alunos!<\/p>\n<p style=\"text-align: right;\"><em>Prof.\u00aa Ivone Oliveira<\/em><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-17065\" src=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/02\/money-quiz-fev22-1.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/02\/money-quiz-fev22-1.jpg 1200w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/02\/money-quiz-fev22-1-300x200.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/02\/money-quiz-fev22-1-768x512.jpg 768w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/02\/money-quiz-fev22-1-1024x683.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-17064\" src=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/02\/money-quiz-fev22-2.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/02\/money-quiz-fev22-2.jpg 1200w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/02\/money-quiz-fev22-2-300x200.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/02\/money-quiz-fev22-2-768x512.jpg 768w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2022\/02\/money-quiz-fev22-2-1024x683.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje, 10 de fevereiro, foi dia de competi\u00e7\u00e3o em literacia financeira! Todos os alunos das turmas do 8.\u00ba ano, inclusive os que nos acompanharam a partir de casa, participaram na competi\u00e7\u00e3o europeia do European Money Quiz (EMQ).<br \/>\nEsta iniciativa, promovida pela Associa\u00e7\u00e3o Portuguesa de Bancos visa promover a literacia financeira dos jovens entre os 13 e os 15 anos e testar os seus conhecimentos em mat\u00e9rias como a poupan\u00e7a, endividamento, gest\u00e3o do or\u00e7amento familiar, seguran\u00e7a digital, entre outras.<br \/>\nForam apurados &#8230;<\/p>\n","protected":false},"author":5,"featured_media":17066,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":9,"footnotes":""},"categories":[95],"tags":[],"class_list":["post-17063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias1718"],"_links":{"self":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/17063"}],"collection":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/comments?post=17063"}],"version-history":[{"count":1,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/17063\/revisions"}],"predecessor-version":[{"id":17067,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/17063\/revisions\/17067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media\/17066"}],"wp:attachment":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media?parent=17063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/categories?post=17063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/tags?post=17063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}