{"id":15227,"date":"2020-02-21T05:02:41","date_gmt":"2020-02-21T05:02:41","guid":{"rendered":"http:\/\/www.csmiguel.pt\/web\/?p=15227"},"modified":"2020-02-21T05:02:41","modified_gmt":"2020-02-21T05:02:41","slug":"na-tvi-e-no-pavilhao-do-conhecimento","status":"publish","type":"post","link":"https:\/\/www.csmiguel.pt\/web\/na-tvi-e-no-pavilhao-do-conhecimento\/","title":{"rendered":"Na TVI e no Pavilh\u00e3o do Conhecimento"},"content":{"rendered":"<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-15229\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2020\/02\/tvi-fev2020-0.png\" alt=\"\" width=\"300\" height=\"200\" \/>Na sexta-feira, dia 14 de fevereiro, os alunos do 8.\u00ba ano foram a Lisboa no \u00e2mbito de uma visita de estudo que ficou dividida em duas partes: da parte da manh\u00e3, visit\u00e1mos as instala\u00e7\u00f5es da TVI e da parte da tarde fomos ao Pavilh\u00e3o do Conhecimento.<\/p>\n<p style=\"text-align: justify;\">Nas instala\u00e7\u00f5es da TVI fomos divididos em 6 grupos e durante a visita de 20 minutos, cada grupo teve a oportunidade de conhecer os est\u00fadios do &#8220;Voc\u00ea na TV&#8221;, &#8220;A Tarde \u00e9 Sua&#8221;, as r\u00e9gies dos est\u00fadios em quest\u00e3o, uma sala com fundo &#8220;greenscreen&#8221; e ainda o espa\u00e7o de trabalho dos jornalistas, onde estava a decorrer o &#8220;Jornal da Uma&#8221;. Enquanto faz\u00edamos esta visita, est\u00e1vamos acompanhados por um guia que, ao longo das instala\u00e7\u00f5es, nos foi explicando como funcionavam os equipamentos, qual era o trabalho realizado e foram-nos, ainda, desvendando alguns segredos e truques do mundo televisivo.<\/p>\n<p style=\"text-align: justify;\">Da parte da tarde, dirigimo-nos ao Pavilh\u00e3o do Conhecimento onde fic\u00e1mos a conhecer a exposi\u00e7\u00e3o \u201cExplora\u201d e a exposi\u00e7\u00e3o tempor\u00e1ria \u201cPum! A vida secreta dos intestinos\u201d. A exposi\u00e7\u00e3o fixa (\u201cExplora\u201d), cont\u00e9m experi\u00eancias acerca da luz, vis\u00e3o, ondas, perce\u00e7\u00e3o e sistemas mais complicados. Aqui foi-nos proposto realizar estas experi\u00eancias curiosas e tirar conclus\u00f5es sobre as mesmas. A exposi\u00e7\u00e3o tempor\u00e1ria tinha como objetivo mostrar-nos o interior dos intestinos, como se os tiv\u00e9ssemos a observar atrav\u00e9s de um raio-X, e ainda falar-nos das mais de 100 mil milh\u00f5es de bact\u00e9rias que carregamos nos intestinos.<br \/>\nEsta ida a Lisboa, em \u00e2mbito escolar, permitiu aos alunos compreender a din\u00e2mica do mundo televisivo e suscitou em n\u00f3s a curiosidade sobre o mundo do jornalismo, manifestando-se esta como uma poss\u00edvel \u00e1rea profissional para alguns de n\u00f3s, ao mesmo tempo que despertou tamb\u00e9m um maior interesse sobre a Ci\u00eancia.<\/p>\n<p style=\"text-align: right;\"><em>Ana Sofia Santos, 8.\u00ba C<\/em><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-15228\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2020\/02\/tvi-fev2020-1.jpg\" alt=\"\" width=\"1200\" height=\"900\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2020\/02\/tvi-fev2020-1.jpg 1200w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2020\/02\/tvi-fev2020-1-300x225.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2020\/02\/tvi-fev2020-1-768x576.jpg 768w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2020\/02\/tvi-fev2020-1-1024x768.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na sexta-feira, dia 14 de fevereiro, os alunos do 8.\u00ba ano foram a Lisboa no \u00e2mbito de uma visita de estudo que ficou dividida em duas partes: da parte da manh\u00e3, visit\u00e1mos as instala\u00e7\u00f5es da TVI e da parte da tarde fomos ao Pavilh\u00e3o do Conhecimento.<br \/>\nNas instala\u00e7\u00f5es da TVI fomos divididos em 6 grupos e durante a visita de 20 minutos, cada grupo teve a oportunidade de conhecer os est\u00fadios do &#8220;Voc\u00ea na TV&#8221;, &#8220;A Tarde \u00e9 Sua&#8221;, as &#8230;<\/p>\n","protected":false},"author":5,"featured_media":15229,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":25,"footnotes":""},"categories":[95],"tags":[],"class_list":["post-15227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias1718"],"_links":{"self":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/15227"}],"collection":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/comments?post=15227"}],"version-history":[{"count":1,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/15227\/revisions"}],"predecessor-version":[{"id":15230,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/15227\/revisions\/15230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media\/15229"}],"wp:attachment":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media?parent=15227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/categories?post=15227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/tags?post=15227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}