{"id":14444,"date":"2019-09-27T15:38:03","date_gmt":"2019-09-27T15:38:03","guid":{"rendered":"http:\/\/www.csmiguel.pt\/web\/?p=14444"},"modified":"2019-09-27T15:38:03","modified_gmt":"2019-09-27T15:38:03","slug":"dia-europeu-da-linguas","status":"publish","type":"post","link":"https:\/\/www.csmiguel.pt\/web\/dia-europeu-da-linguas\/","title":{"rendered":"Dia Europeu da L\u00ednguas"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/09\/linguas-set19-0.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-14446\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/09\/linguas-set19-0.png\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>Numa altura em que tanto se fala e se sente a necessidade de compet\u00eancias lingu\u00edsticas, essenciais para garantir a equidade e a integra\u00e7\u00e3o, o Col\u00e9gio de S\u00e3o Miguel dinamizou algumas atividades para assinalar o Dia Europeu das L\u00ednguas que se celebra sempre, no dia 26 de setembro.<\/p>\n<p style=\"text-align: justify;\">\u201cNa atual conjuntura de crescente mobilidade, globaliza\u00e7\u00e3o da economia e tend\u00eancias econ\u00f3micas em constante mudan\u00e7a, \u00e9 mais \u00f3bvia do que nunca a necessidade de aprender l\u00ednguas e desenvolver uma compet\u00eancia plurilingue e intercultural.\u201d E foi, com esse intuito que os nossos alunos fizeram desenhos, maquetas, onde representaram o som dos animais nas diferentes l\u00ednguas, recolheram prov\u00e9rbios apresentaram-nos \u00e0 restante comunidade educativa.<\/p>\n<p style=\"text-align: justify;\">Como o saber n\u00e3o ocupa lugar, vale sempre a pena aprender uma nova l\u00edngua estrangeira!<\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/09\/linguas-set19-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-14445\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/09\/linguas-set19-1.jpg\" alt=\"\" width=\"1200\" height=\"900\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/09\/linguas-set19-1.jpg 1200w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/09\/linguas-set19-1-300x225.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/09\/linguas-set19-1-768x576.jpg 768w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/09\/linguas-set19-1-1024x768.jpg 1024w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Numa altura em que tanto se fala e se sente a necessidade de compet\u00eancias lingu\u00edsticas, essenciais para garantir a equidade e a integra\u00e7\u00e3o, o Col\u00e9gio de S\u00e3o Miguel dinamizou algumas atividades para assinalar o Dia Europeu das L\u00ednguas que se celebra sempre, no dia 26 de setembro.<br \/>\n\u201cNa atual conjuntura de crescente mobilidade, globaliza\u00e7\u00e3o da economia e tend\u00eancias econ\u00f3micas em constante mudan\u00e7a, \u00e9 mais \u00f3bvia do que nunca a necessidade de aprender l\u00ednguas e desenvolver uma compet\u00eancia plurilingue e intercultural.\u201d &#8230;<\/p>\n","protected":false},"author":1,"featured_media":14446,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":39,"footnotes":""},"categories":[95],"tags":[],"class_list":["post-14444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias1718"],"_links":{"self":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/14444"}],"collection":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/comments?post=14444"}],"version-history":[{"count":1,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/14444\/revisions"}],"predecessor-version":[{"id":14447,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/14444\/revisions\/14447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media\/14446"}],"wp:attachment":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media?parent=14444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/categories?post=14444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/tags?post=14444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}