{"id":14300,"date":"2019-06-11T14:56:42","date_gmt":"2019-06-11T14:56:42","guid":{"rendered":"http:\/\/www.csmiguel.pt\/web\/?p=14300"},"modified":"2019-06-11T14:56:42","modified_gmt":"2019-06-11T14:56:42","slug":"appa-final","status":"publish","type":"post","link":"https:\/\/www.csmiguel.pt\/web\/appa-final\/","title":{"rendered":"APPA Final"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-0.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-14306\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-0.png\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>\u201cOs in\u00edcios t\u00eam uma intensidade de vazio. Talvez o princ\u00edpio possa ser comparado a uma casa vazia que s\u00f3 \u00e9 inabitada. Inabitada de coisas e pessoas, habitada de sil\u00eancios. O sil\u00eancio \u00e9 um instrumento de constru\u00e7\u00e3o, uma lente, uma alavanca, \u00e9 um tra\u00e7o de uni\u00e3o, mais frequente do que se imagina e mais fecundo do que se julga.\u201d<\/em><\/p>\n<p style=\"text-align: justify;\">Este foi o mote para a Festa de final de ano letivo do Col\u00e9gio de S\u00e3o Miguel que voltou a ser, sete anos depois, no Centro Pastoral de Paulo VI e que contou com a presen\u00e7a de Sua Emin\u00eancia Cardeal D. Ant\u00f3nio Marto e do Reitor e Vice-Reitor do Santu\u00e1rio de F\u00e1tima, Padre Carlos Cabecinhas e Padre V\u00edtor Coutinho, respetivamente.<\/p>\n<p style=\"text-align: justify;\">No dia 7 de junho, pelas 21h, mais de 2000 pessoas encheram a sala para assistirem a um espet\u00e1culo de luz, cor, som e muito movimento que procurou despertar todos os sentidos de quem estava a assistir e transmitir a mensagem de que, numa \u00e9poca de ru\u00eddos, o sil\u00eancio \u00e9 fundamental e ensinamos muito! Os protagonistas foram os mais de 200 alunos em palco, do 5.\u00ba ao 12.\u00ba ano, para al\u00e9m de dois antigos alunos que vieram abrilhantar, ainda mais, a nossa festa e recordar tempos passados!<\/p>\n<p style=\"text-align: justify;\">Uma noite de grandes emo\u00e7\u00f5es que jamais iremos esquecer!<\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-14312\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-1.jpg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-14305\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-2.jpg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14305\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-3.jpg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14305\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-4.jpg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14305\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-5.jpg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14305\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-6.jpg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14305\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-7.jpg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14305\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-8.jpg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14305\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-9.jpg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-10.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14305\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-10.jpg\" alt=\"\" width=\"1280\" height=\"853\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14305\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-11.jpg\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-11.jpg 1280w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-11-300x200.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-11-768x512.jpg 768w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/06\/appa-jun19-11-1024x682.jpg 1024w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cOs in\u00edcios t\u00eam uma intensidade de vazio. Talvez o princ\u00edpio possa ser comparado a uma casa vazia que s\u00f3 \u00e9 inabitada. Inabitada de coisas e pessoas, habitada de sil\u00eancios. O sil\u00eancio \u00e9 um instrumento de constru\u00e7\u00e3o, uma lente, uma alavanca, \u00e9 um tra\u00e7o de uni\u00e3o, mais frequente do que se imagina e mais fecundo do que se julga.\u201d<br \/>\nEste foi o mote para a Festa de final de ano letivo do Col\u00e9gio de S\u00e3o Miguel que voltou a ser, sete &#8230;<\/p>\n","protected":false},"author":1,"featured_media":14306,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":9,"footnotes":""},"categories":[95],"tags":[],"class_list":["post-14300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias1718"],"_links":{"self":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/14300"}],"collection":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/comments?post=14300"}],"version-history":[{"count":1,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/14300\/revisions"}],"predecessor-version":[{"id":14313,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/14300\/revisions\/14313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media\/14306"}],"wp:attachment":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media?parent=14300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/categories?post=14300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/tags?post=14300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}