{"id":14064,"date":"2019-03-12T23:58:43","date_gmt":"2019-03-12T23:58:43","guid":{"rendered":"http:\/\/www.csmiguel.pt\/web\/?p=14064"},"modified":"2019-03-12T23:58:43","modified_gmt":"2019-03-12T23:58:43","slug":"nos-passos-de-jesus","status":"publish","type":"post","link":"https:\/\/www.csmiguel.pt\/web\/nos-passos-de-jesus\/","title":{"rendered":"Nos Passos de Jesus"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/03\/passos-mar19-0.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-14067\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/03\/passos-mar19-0.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>Nos dias 7 e 8 de mar\u00e7o, demos in\u00edcio \u00e0 nossa caminhada quaresmal no col\u00e9gio, com as Celebra\u00e7\u00f5es Penitenciais. Toda a comunidade, de um modo especial os alunos, foi convidada a participar numa reflex\u00e3o sobre o sentido da Quaresma, preparada por alguns alunos das turmas do 11.\u00ba ano de Ci\u00eancias e do 12.\u00ba de Artes, e a celebrar o Sacramento do Perd\u00e3o junto dos sacerdotes que acederam ao convite para estarem presentes.<\/p>\n<p style=\"text-align: justify;\">Agradecemos a generosidade daqueles que se empenharam na dinamiza\u00e7\u00e3o desta atividade e desejamos a todos uma Santa Quaresma.<\/p>\n<p style=\"text-align: right;\"><em>Prof.\u00aa Ana Alexandra Ferreira<\/em><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/03\/passos-mar19-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-14066\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/03\/passos-mar19-1.jpg\" alt=\"\" width=\"830\" height=\"623\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/03\/passos-mar19-1.jpg 830w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/03\/passos-mar19-1-300x225.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/03\/passos-mar19-1-768x576.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/03\/passos-mar19-2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-14065\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/03\/passos-mar19-2.jpg\" alt=\"\" width=\"830\" height=\"623\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/03\/passos-mar19-2.jpg 830w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/03\/passos-mar19-2-300x225.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/03\/passos-mar19-2-768x576.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos dias 7 e 8 de mar\u00e7o, demos in\u00edcio \u00e0 nossa caminhada quaresmal no col\u00e9gio, com as Celebra\u00e7\u00f5es Penitenciais. Toda a comunidade, de um modo especial os alunos, foi convidada a participar numa reflex\u00e3o sobre o sentido da Quaresma, preparada por alguns alunos das turmas do 11.\u00ba ano de Ci\u00eancias e do 12.\u00ba de Artes, e a celebrar o Sacramento do Perd\u00e3o junto dos sacerdotes que acederam ao convite para estarem presentes.<br \/>\nAgradecemos a generosidade daqueles que se empenharam na &#8230;<\/p>\n","protected":false},"author":1,"featured_media":14067,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":3,"footnotes":""},"categories":[95],"tags":[],"class_list":["post-14064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias1718"],"_links":{"self":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/14064"}],"collection":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/comments?post=14064"}],"version-history":[{"count":1,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/14064\/revisions"}],"predecessor-version":[{"id":14068,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/14064\/revisions\/14068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media\/14067"}],"wp:attachment":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media?parent=14064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/categories?post=14064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/tags?post=14064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}