{"id":13842,"date":"2019-01-20T18:15:07","date_gmt":"2019-01-20T18:15:07","guid":{"rendered":"http:\/\/www.csmiguel.pt\/web\/?p=13842"},"modified":"2019-01-20T18:15:48","modified_gmt":"2019-01-20T18:15:48","slug":"aprender-com-os-robots","status":"publish","type":"post","link":"https:\/\/www.csmiguel.pt\/web\/aprender-com-os-robots\/","title":{"rendered":"Aprender com os Robots"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/01\/robots-jan19-0.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-13844\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/01\/robots-jan19-0.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a>No \u00e2mbito da inova\u00e7\u00e3o pedag\u00f3gica que nos caracteriza, o Col\u00e9gio de S\u00e3o Miguel renovou as suas ferramentas pedag\u00f3gicas para o ensino da programa\u00e7\u00e3o, nas disciplinas TIC.<\/p>\n<p style=\"text-align: justify;\">O mBot Makeblok \u00e9 um robot educacional que permite que os nossos alunos possam dar os primeiros passos ao n\u00edvel da programa\u00e7\u00e3o, da eletr\u00f3nica e da rob\u00f3tica. O mBot \u00e9 de f\u00e1cil montagem e oferece infinitas possibilidades de aprender STEM (Ci\u00eancia, Tecnologia, Engenharia, Matem\u00e1tica). Para al\u00e9m disso, o software mBlock de programa\u00e7\u00e3o gr\u00e1fica drag-and-drop, desenvolvido com base no Scratch 2.0, fornece uma maneira r\u00e1pida de aprender a programa\u00e7\u00e3o, controlar o robot e realizar v\u00e1rias fun\u00e7\u00f5es; neste momento, est\u00e1 a ser utilizado pelos alunos do 2.\u00ba e 3.\u00ba ciclo.<\/p>\n<p style=\"text-align: justify;\">As partes eletr\u00f3nicas do mBot s\u00e3o desenvolvidas com base no sistema de c\u00f3digo aberto Arduino o que garante que o mBot seja bastante vers\u00e1til e permita diferentes aprendizagens aos alunos mais velhos.<\/p>\n<div style=\"width: 1920px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-13842-1\" width=\"1920\" height=\"1080\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/01\/VID_20190116_120932.mp4?_=1\" \/><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/01\/VID_20190116_120932.mp4\">https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/01\/VID_20190116_120932.mp4<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/01\/robots-jan19-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-13843\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2019\/01\/robots-jan19-1.jpg\" alt=\"\" width=\"830\" height=\"553\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/01\/robots-jan19-1.jpg 830w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/01\/robots-jan19-1-300x200.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2019\/01\/robots-jan19-1-768x512.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No \u00e2mbito da inova\u00e7\u00e3o pedag\u00f3gica que nos caracteriza, o Col\u00e9gio de S\u00e3o Miguel renovou as suas ferramentas pedag\u00f3gicas para o ensino da programa\u00e7\u00e3o, nas disciplinas TIC.<br \/>\nO mBot Makeblok \u00e9 um robot educacional que permite que os nossos alunos possam dar os primeiros passos ao n\u00edvel da programa\u00e7\u00e3o, da eletr\u00f3nica e da rob\u00f3tica. O mBot \u00e9 de f\u00e1cil montagem e oferece infinitas possibilidades de aprender STEM (Ci\u00eancia, Tecnologia, Engenharia, Matem\u00e1tica). Para al\u00e9m disso, o software mBlock de programa\u00e7\u00e3o gr\u00e1fica drag-and-drop, &#8230;<\/p>\n","protected":false},"author":1,"featured_media":13844,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":60,"footnotes":""},"categories":[95],"tags":[],"class_list":["post-13842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias1718"],"_links":{"self":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/13842"}],"collection":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/comments?post=13842"}],"version-history":[{"count":2,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/13842\/revisions"}],"predecessor-version":[{"id":13847,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/13842\/revisions\/13847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media\/13844"}],"wp:attachment":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media?parent=13842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/categories?post=13842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/tags?post=13842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}