{"id":13554,"date":"2018-11-02T12:11:37","date_gmt":"2018-11-02T12:11:37","guid":{"rendered":"http:\/\/www.csmiguel.pt\/web\/?p=13554"},"modified":"2018-11-06T19:08:56","modified_gmt":"2018-11-06T19:08:56","slug":"ajo-no-conselho-de-ourem","status":"publish","type":"post","link":"https:\/\/www.csmiguel.pt\/web\/ajo-no-conselho-de-ourem\/","title":{"rendered":"AJO no concelho de Our\u00e9m"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-0.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-13557\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-0.jpg\" alt=\"\" width=\"330\" height=\"220\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-0.jpg 330w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-0-300x200.jpg 300w\" sizes=\"(max-width: 330px) 100vw, 330px\" \/><\/a>No dia 25 de outubro, os alunos do 10.\u00ba ano dos cursos de Ci\u00eancias e Tecnologias e L\u00ednguas e Humanidades e os representantes de cada turma do 9.\u00ba ano reuniram-se no audit\u00f3rio D. Jo\u00e3o Pereira Ven\u00e2ncio para assistir a uma palestra sobre o projeto \u201dAJO\u201d, que se inicia neste ano, presidida pelo Dr. Jo\u00e3o Moura, presidente da Assembleia Municipal de Our\u00e9m.<\/p>\n<p style=\"text-align: justify;\">Foi lan\u00e7ado o desafio de realizar um Parlamento de Jovens de Our\u00e9m centrado em temas significativos para o concelho de modo a dar reconhecimento \u00e0 nossa regi\u00e3o atrav\u00e9s da promo\u00e7\u00e3o e valoriza\u00e7\u00e3o do seu Patrim\u00f3nio. O grande objetivo \u00e9 incutir o esp\u00edrito de amor pela nossa terra dedicando tempo ao bem comum e, por sua vez, deix\u00e1-la um pouco melhor do que a encontr\u00e1mos, nunca esquecendo o que marca a nossa identidade e realidade. Este projeto est\u00e1 dividido em diversas fases de sele\u00e7\u00e3o, em que uma delas inclui um debate de ideias entre as escolas de Our\u00e9m, sendo que a proposta escolhida ser\u00e1 apresentada pelo grupo vencedor, na Assembleia Geral de Our\u00e9m.<\/p>\n<p style=\"text-align: justify;\">Segundo as palavras do Sr. Presidente, temos de \u201cagir para o concelho\u201d. Agora pergunto: e tu, vais agir?<\/p>\n<p style=\"text-align: center;\"><strong>#ETUVAISAGIR<\/strong><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-13556\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-1.jpg\" alt=\"\" width=\"830\" height=\"524\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-1.jpg 830w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-1-300x189.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-1-768x485.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-13555\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-2.jpg\" alt=\"\" width=\"830\" height=\"528\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-2.jpg 830w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-2-300x191.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/11\/ajo-out18-2-768x489.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 25 de outubro, os alunos do 10.\u00ba ano dos cursos de Ci\u00eancias e Tecnologias e L\u00ednguas e Humanidades e os representantes de cada turma do 9.\u00ba ano reuniram-se no audit\u00f3rio D. Jo\u00e3o Pereira Ven\u00e2ncio para assistir a uma palestra sobre o projeto \u201dAJO\u201d, que se inicia neste ano, presidida pelo Dr. Jo\u00e3o Moura, presidente da Assembleia Municipal de Our\u00e9m.<br \/>\nFoi lan\u00e7ado o desafio de realizar um Parlamento de Jovens de Our\u00e9m centrado em temas significativos para o concelho &#8230;<\/p>\n","protected":false},"author":1,"featured_media":13557,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":6,"footnotes":""},"categories":[95],"tags":[],"class_list":["post-13554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias1718"],"_links":{"self":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/13554"}],"collection":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/comments?post=13554"}],"version-history":[{"count":2,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/13554\/revisions"}],"predecessor-version":[{"id":13573,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/13554\/revisions\/13573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media\/13557"}],"wp:attachment":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media?parent=13554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/categories?post=13554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/tags?post=13554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}