{"id":13439,"date":"2018-09-12T23:40:18","date_gmt":"2018-09-12T23:40:18","guid":{"rendered":"http:\/\/www.csmiguel.pt\/web\/?p=13439"},"modified":"2018-09-12T23:41:08","modified_gmt":"2018-09-12T23:41:08","slug":"de-volta-a-escola","status":"publish","type":"post","link":"https:\/\/www.csmiguel.pt\/web\/de-volta-a-escola\/","title":{"rendered":"De volta \u00e0 escola!!!"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-full wp-image-13443\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18.jpg\" alt=\"\" width=\"330\" height=\"220\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18.jpg 330w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18-300x200.jpg 300w\" sizes=\"(max-width: 330px) 100vw, 330px\" \/><\/a>Todos os alunos dos cursos com Planos Pr\u00f3prios regressaram \u00e0 escola, hoje, dia 12 de setembro, para mais um ano letivo que, acreditamos, ir\u00e1 ser muito proveitoso.<\/p>\n<p style=\"text-align: justify;\">Orientados pelo lema \u201cAposta em ti. Confia. Caminhamos juntos.\u201d, os alunos foram convidados pelo nosso director, Dr. Manuel Louren\u00e7o, a assumi-lo, a n\u00e3o ter medo porque ningu\u00e9m vai estar s\u00f3 e a ver o futuro como uma constru\u00e7\u00e3o que come\u00e7a Agora&#8230;<\/p>\n<p style=\"text-align: justify;\">Depois de um breve encontro com os Diretores de Turma, cada curso teve um encontro com profissionais das respectivas \u00e1reas e com antigos alunos que vieram mostrar a sua vis\u00e3o de cada \u00e1rea profissional.<\/p>\n<p style=\"text-align: justify;\">No fim do dia, houve tempo para um lanche no bar\u2026 para \u201crecarregar\u201d energias para aquilo que nos espera!<\/p>\n<p style=\"text-align: justify;\">N\u00e3o h\u00e1 tempo a perder!<\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_1.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-13442\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_1.jpg\" alt=\"\" width=\"830\" height=\"553\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_1.jpg 830w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_1-300x200.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_1-768x512.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-13441\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_2.jpg\" alt=\"\" width=\"830\" height=\"553\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_2.jpg 830w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_2-300x200.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_2-768x512.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-13440\" src=\"https:\/\/csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_3.jpg\" alt=\"\" width=\"830\" height=\"467\" srcset=\"https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_3.jpg 830w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_3-300x169.jpg 300w, https:\/\/www.csmiguel.pt\/web\/wp-content\/uploads\/2018\/09\/de_volta_a_escola_set18_3-768x432.jpg 768w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos os alunos dos cursos com Planos Pr\u00f3prios regressaram \u00e0 escola, hoje, dia 12 de setembro, para mais um ano letivo que, acreditamos, ir\u00e1 ser muito proveitoso.<br \/>\nOrientados pelo lema \u201cAposta em ti. Confia. Caminhamos juntos.\u201d, os alunos foram convidados pelo nosso director, Dr. Manuel Louren\u00e7o, a assumi-lo, a n\u00e3o ter medo porque ningu\u00e9m vai estar s\u00f3 e a ver o futuro como uma constru\u00e7\u00e3o que come\u00e7a Agora&#8230;<br \/>\nDepois de um breve encontro com os Diretores de Turma, cada curso &#8230;<\/p>\n","protected":false},"author":1,"featured_media":13443,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_meta":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":4,"footnotes":""},"categories":[95,1],"tags":[],"class_list":["post-13439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias1718","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/13439"}],"collection":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/comments?post=13439"}],"version-history":[{"count":1,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/13439\/revisions"}],"predecessor-version":[{"id":13444,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/posts\/13439\/revisions\/13444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media\/13443"}],"wp:attachment":[{"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/media?parent=13439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/categories?post=13439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.csmiguel.pt\/web\/wp-json\/wp\/v2\/tags?post=13439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}